{"id":411,"count":1,"description":"","link":"https:\/\/solidarity.international\/index.php\/tag\/berlin\/","name":"Berlin","slug":"berlin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/tags\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/posts?tags=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}