{"id":284,"count":2,"description":"","link":"https:\/\/solidarity.international\/index.php\/tag\/usa-2015\/","name":"USA","slug":"usa-2015","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/tags\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/solidarity.international\/index.php\/wp-json\/wp\/v2\/posts?tags=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}